{"id":1,"count":198,"description":"","link":"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/","name":"Misc","slug":"misc","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Misc Archives - Orderoo Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Misc Archives - Orderoo Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/\" \/>\n<meta property=\"og:site_name\" content=\"Orderoo Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/\",\"url\":\"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/\",\"name\":\"Misc Archives - Orderoo Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.orderoo.com.au\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.orderoo.com.au\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Misc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.orderoo.com.au\/blog\/#website\",\"url\":\"https:\/\/www.orderoo.com.au\/blog\/\",\"name\":\"Orderoo Blog | On Demand Services Updates\",\"description\":\"Discover, Learn, and Explore\",\"publisher\":{\"@id\":\"https:\/\/www.orderoo.com.au\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.orderoo.com.au\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.orderoo.com.au\/blog\/#organization\",\"name\":\"Orderoo Blog | On Demand Services Updates\",\"url\":\"https:\/\/www.orderoo.com.au\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.orderoo.com.au\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.orderoo.com.au\/blog\/wp-content\/uploads\/2023\/06\/cropped-aSDasdASD.png\",\"contentUrl\":\"https:\/\/www.orderoo.com.au\/blog\/wp-content\/uploads\/2023\/06\/cropped-aSDasdASD.png\",\"width\":200,\"height\":50,\"caption\":\"Orderoo Blog | On Demand Services Updates\"},\"image\":{\"@id\":\"https:\/\/www.orderoo.com.au\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Misc Archives - Orderoo Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/","og_locale":"en_US","og_type":"article","og_title":"Misc Archives - Orderoo Blog","og_url":"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/","og_site_name":"Orderoo Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/","url":"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/","name":"Misc Archives - Orderoo Blog","isPartOf":{"@id":"https:\/\/www.orderoo.com.au\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.orderoo.com.au\/blog\/category\/misc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.orderoo.com.au\/blog\/"},{"@type":"ListItem","position":2,"name":"Misc"}]},{"@type":"WebSite","@id":"https:\/\/www.orderoo.com.au\/blog\/#website","url":"https:\/\/www.orderoo.com.au\/blog\/","name":"Orderoo Blog | On Demand Services Updates","description":"Discover, Learn, and Explore","publisher":{"@id":"https:\/\/www.orderoo.com.au\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.orderoo.com.au\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.orderoo.com.au\/blog\/#organization","name":"Orderoo Blog | On Demand Services Updates","url":"https:\/\/www.orderoo.com.au\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.orderoo.com.au\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.orderoo.com.au\/blog\/wp-content\/uploads\/2023\/06\/cropped-aSDasdASD.png","contentUrl":"https:\/\/www.orderoo.com.au\/blog\/wp-content\/uploads\/2023\/06\/cropped-aSDasdASD.png","width":200,"height":50,"caption":"Orderoo Blog | On Demand Services Updates"},"image":{"@id":"https:\/\/www.orderoo.com.au\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.orderoo.com.au\/blog\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orderoo.com.au\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.orderoo.com.au\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.orderoo.com.au\/blog\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}